{"id":1052,"date":"2023-05-24T13:08:17","date_gmt":"2023-05-24T12:08:17","guid":{"rendered":"https:\/\/www.image7.fr\/?post_type=document&amp;p=1052"},"modified":"2023-05-24T13:08:17","modified_gmt":"2023-05-24T12:08:17","slug":"test-agencedebord","status":"publish","type":"document","link":"https:\/\/www.image7.fr\/en\/document\/test-agencedebord\/","title":{"rendered":"Meta condamn\u00e9"},"content":{"rendered":"<h4>Tech et Caetera #14 | 24 MAI 2023<\/h4>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/images.pexels.com\/photos\/267399\/pexels-photo-267399.jpeg?auto=compress&amp;cs=tinysrgb&amp;w=1260&amp;h=750&amp;dpr=1\" alt=\"Gratuit Logo Facebook Photos\" width=\"310\" height=\"195\" \/>C&rsquo;est une amende record qui sonne comme un coup de tonnerre. Lundi 22 mai, la Data Protection Commission, \u00e9quivalent irlandais de notre CNIL, a inflig\u00e9 \u00e0 Meta une amende d&rsquo;1,2 milliards d&rsquo;euros pour avoir continu\u00e9 \u00e0 transf\u00e9rer les donn\u00e9es d&rsquo;utilisateurs europ\u00e9ens de Facebook vers des serveurs localis\u00e9s aux \u00c9tats-Unis. La DPC a \u00e9galement ordonn\u00e9 \u00e0 Meta de suspendre tout transfert de donn\u00e9es personnelles vers les \u00c9tats-Unis dans les cinq mois. Il s&rsquo;agit de la sanction la plus forte jamais impos\u00e9e en Europe, depuis l&rsquo;amende de 746 millions d&rsquo;euros inflig\u00e9e \u00e0 Amazon au Luxembourg, en juin 2021. Un coup dur pour Meta, mais qui ne mettra pas en risque la compagnie, dont le chiffre d&rsquo;affaires au premier trimestre 2023 s&rsquo;\u00e9leve \u00e0 28,7 milliards de dollars (26,7 milliards d&rsquo;euros).<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Nick Clegg, responsable des affaires publiques de Meta, a annonc\u00e9 que le groupe allait faire appel de cette d\u00e9cision, rapporte Le Monde. Selon lui, elle constitue \u00ab\u00a0un dangereux pr\u00e9c\u00e9dent pour les nombreuses entreprises qui transf\u00e8rent des donn\u00e9es entre les \u00c9tats-Unis et l\u2019UE\u00a0\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>A l&rsquo;heure de la r\u00e9volution de l&rsquo;IA, on peut en effet s&rsquo;interroger sur la persistance de r\u00e8gles du jeu diff\u00e9rentes en mati\u00e8re de donn\u00e9es de chaque c\u00f4t\u00e9 de l&rsquo;Atlantique, et \u00e0 leurs cons\u00e9quences potentielles pour l&rsquo;\u00e9conomie. Interrog\u00e9e par Radio France, Florence G\u2019Sell, titulaire de la Chaire Digital, Gouvernance et Souverainet\u00e9 de Sciences Po rappelle qu&rsquo;au-del\u00e0 de Facebook, \u00ab\u00a0cette d\u00e9cision concerne aussi toutes les entreprises technologiques qui travaillent \u00e0 partir des donn\u00e9es et qui, pour un grand nombre d&rsquo;entre elles, ont besoin de pouvoir les faire circuler\u00a0\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Pendant ce temps, les associations de d\u00e9fense de la vie priv\u00e9e europ\u00e9ennes pointent du doigt la lenteur des proc\u00e9dures et reprochent aux autorit\u00e9s leur incapacit\u00e9 \u00e0 faire appliquer les sanctions. Le quotidien suisse Le Temps rappelle que la d\u00e9cision de la DPC intervient \u201cen plein vide juridique\u201d. En effet, les Etats-Unis et l&rsquo;Europe sont en train de n\u00e9gocier un nouvel accord. La Commission europ\u00e9enne esp\u00e8re adopter un texte \u00ab\u00a0d&rsquo;ici l&rsquo;\u00e9t\u00e9\u00a0\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Que se passera-t-il si aucun compromis n&rsquo;est trouv\u00e9 ? Meta devrait supprimer toutes les donn\u00e9es des utilisateurs de l&rsquo;UE stock\u00e9es aux \u00c9tats-Unis. C&rsquo;est bien peu probable pour la plupart des observateurs, voire impossible, de l&rsquo;aveu m\u00eame des ing\u00e9nieurs de l&rsquo;entreprise.<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false},"categorie_documents":[39],"class_list":["post-1052","document","type-document","status-publish","hentry","categorie_documents-tech-et-caetera"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Meta condamn\u00e9 - Image Sept<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.image7.fr\/en\/document\/test-agencedebord\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meta condamn\u00e9 - Image Sept\" \/>\n<meta property=\"og:description\" content=\"Tech et Caetera #14 | 24 MAI 2023 &nbsp; C&rsquo;est une amende record qui sonne comme un coup de tonnerre. Lundi 22 mai, la Data Protection Commission, \u00e9quivalent irlandais de notre CNIL, a inflig\u00e9 \u00e0 Meta une amende d&rsquo;1,2 milliards d&rsquo;euros pour avoir continu\u00e9 \u00e0 transf\u00e9rer les donn\u00e9es d&rsquo;utilisateurs europ\u00e9ens de Facebook vers des serveurs [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.image7.fr\/en\/document\/test-agencedebord\/\" \/>\n<meta property=\"og:site_name\" content=\"Image Sept\" \/>\n<meta property=\"og:image\" content=\"https:\/\/images.pexels.com\/photos\/267399\/pexels-photo-267399.jpeg?auto=compress&amp;cs=tinysrgb&amp;w=1260&amp;h=750&amp;dpr=1\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.image7.fr\/en\/document\/test-agencedebord\/\",\"url\":\"https:\/\/www.image7.fr\/en\/document\/test-agencedebord\/\",\"name\":\"Meta condamn\u00e9 - Image Sept\",\"isPartOf\":{\"@id\":\"https:\/\/www.image7.fr\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.image7.fr\/en\/document\/test-agencedebord\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.image7.fr\/en\/document\/test-agencedebord\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/images.pexels.com\/photos\/267399\/pexels-photo-267399.jpeg?auto=compress&amp;cs=tinysrgb&amp;w=1260&amp;h=750&amp;dpr=1\",\"datePublished\":\"2023-05-24T12:08:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.image7.fr\/en\/document\/test-agencedebord\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.image7.fr\/en\/document\/test-agencedebord\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.image7.fr\/en\/document\/test-agencedebord\/#primaryimage\",\"url\":\"https:\/\/images.pexels.com\/photos\/267399\/pexels-photo-267399.jpeg?auto=compress&amp;cs=tinysrgb&amp;w=1260&amp;h=750&amp;dpr=1\",\"contentUrl\":\"https:\/\/images.pexels.com\/photos\/267399\/pexels-photo-267399.jpeg?auto=compress&amp;cs=tinysrgb&amp;w=1260&amp;h=750&amp;dpr=1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.image7.fr\/en\/document\/test-agencedebord\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.image7.fr\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Document\",\"item\":\"https:\/\/www.image7.fr\/en\/document\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Meta condamn\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.image7.fr\/en\/#website\",\"url\":\"https:\/\/www.image7.fr\/en\/\",\"name\":\"Image Sept\",\"description\":\"Un site utilisant R\u00e9seau Image 7\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.image7.fr\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Meta condamn\u00e9 - Image Sept","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.image7.fr\/en\/document\/test-agencedebord\/","og_locale":"fr_FR","og_type":"article","og_title":"Meta condamn\u00e9 - Image Sept","og_description":"Tech et Caetera #14 | 24 MAI 2023 &nbsp; C&rsquo;est une amende record qui sonne comme un coup de tonnerre. Lundi 22 mai, la Data Protection Commission, \u00e9quivalent irlandais de notre CNIL, a inflig\u00e9 \u00e0 Meta une amende d&rsquo;1,2 milliards d&rsquo;euros pour avoir continu\u00e9 \u00e0 transf\u00e9rer les donn\u00e9es d&rsquo;utilisateurs europ\u00e9ens de Facebook vers des serveurs [&hellip;]","og_url":"https:\/\/www.image7.fr\/en\/document\/test-agencedebord\/","og_site_name":"Image Sept","og_image":[{"url":"https:\/\/images.pexels.com\/photos\/267399\/pexels-photo-267399.jpeg?auto=compress&amp;cs=tinysrgb&amp;w=1260&amp;h=750&amp;dpr=1","type":"","width":"","height":""}],"twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.image7.fr\/en\/document\/test-agencedebord\/","url":"https:\/\/www.image7.fr\/en\/document\/test-agencedebord\/","name":"Meta condamn\u00e9 - Image Sept","isPartOf":{"@id":"https:\/\/www.image7.fr\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.image7.fr\/en\/document\/test-agencedebord\/#primaryimage"},"image":{"@id":"https:\/\/www.image7.fr\/en\/document\/test-agencedebord\/#primaryimage"},"thumbnailUrl":"https:\/\/images.pexels.com\/photos\/267399\/pexels-photo-267399.jpeg?auto=compress&amp;cs=tinysrgb&amp;w=1260&amp;h=750&amp;dpr=1","datePublished":"2023-05-24T12:08:17+00:00","breadcrumb":{"@id":"https:\/\/www.image7.fr\/en\/document\/test-agencedebord\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.image7.fr\/en\/document\/test-agencedebord\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.image7.fr\/en\/document\/test-agencedebord\/#primaryimage","url":"https:\/\/images.pexels.com\/photos\/267399\/pexels-photo-267399.jpeg?auto=compress&amp;cs=tinysrgb&amp;w=1260&amp;h=750&amp;dpr=1","contentUrl":"https:\/\/images.pexels.com\/photos\/267399\/pexels-photo-267399.jpeg?auto=compress&amp;cs=tinysrgb&amp;w=1260&amp;h=750&amp;dpr=1"},{"@type":"BreadcrumbList","@id":"https:\/\/www.image7.fr\/en\/document\/test-agencedebord\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.image7.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Document","item":"https:\/\/www.image7.fr\/en\/document\/"},{"@type":"ListItem","position":3,"name":"Meta condamn\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.image7.fr\/en\/#website","url":"https:\/\/www.image7.fr\/en\/","name":"Image Sept","description":"Un site utilisant R\u00e9seau Image 7","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.image7.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.image7.fr\/en\/wp-json\/wp\/v2\/document\/1052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.image7.fr\/en\/wp-json\/wp\/v2\/document"}],"about":[{"href":"https:\/\/www.image7.fr\/en\/wp-json\/wp\/v2\/types\/document"}],"wp:attachment":[{"href":"https:\/\/www.image7.fr\/en\/wp-json\/wp\/v2\/media?parent=1052"}],"wp:term":[{"taxonomy":"categorie_documents","embeddable":true,"href":"https:\/\/www.image7.fr\/en\/wp-json\/wp\/v2\/categorie_documents?post=1052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}